{"id":23955,"date":"2019-11-03T12:40:29","date_gmt":"2019-11-03T11:40:29","guid":{"rendered":"https:\/\/perfectvenue.eu\/?p=23955"},"modified":"2019-11-05T12:43:19","modified_gmt":"2019-11-05T11:43:19","slug":"elegant-wedding-madrid","status":"publish","type":"post","link":"https:\/\/perfectvenue.eu\/es\/elegant-wedding-madrid\/","title":{"rendered":"Tu boda con elegancia, encanto y esencia en Real F\u00e1brica de Tapices"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Existen lugares con una esencia especial, una historia&#8230;, espacios singulares donde los eventos se vuelven m\u00e1gicos e irrepetibles. <strong>Real F\u00e1brica de Tapices<\/strong> es uno de esos lugares.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Este espacio <strong>en pleno centro de Madrid, con m\u00e1s de 300 a\u00f1os de historia<\/strong>, nos ofrece un lugar \u00fanico donde llevar a cabo nuestra boda. Rodeados de verdaderas obras de arte, con salas \u00fanicas y exclusivas, una oferta gastron\u00f3mica impecable y con uno de los m\u00e1s pintorescos jardines, Real F\u00e1brica de Tapices se convierte en uno de los referentes de la capital para celebrar un enlace de ensue\u00f1o.<\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24438 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices weddings - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-43.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24705 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-44.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24709 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-65.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24710 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-66.jpg\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Hemos tenido la oportunidad de participar en uno de los enlaces celebrados en este singular espacio, la boda de Alejandro y Elianny, una preciosa pareja que ha querido compartir con todos nosotros uno de los momentos m\u00e1s especiales de su vida, su<strong> \u201cS\u00ed, quiero\u201d en Real F\u00e1brica de Tapices.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Para su d\u00eda especial, Elianny opt\u00f3 por un sencillo pero precioso modelo de Jes\u00fas Peir\u00f3 con tirantes finos, escote cuadrado y cuerpo en encaje bordado, delicado y fino, que da una elegancia especial a la novia. La falda con ca\u00edda, decorada con suaves motivos florales, acaba en una peque\u00f1a cola estilo capilla, c\u00f3moda y funcional, que aporta un punto de distinci\u00f3n al vestido.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El toque original y diferenciador lo aporta un singular ramo, creaci\u00f3n de Monceau Fleurs, con base en hojas verdes y ovillos de algod\u00f3n de diferentes tonos, algod\u00f3n natural y peque\u00f1as flores, que hacen un gui\u00f1o al espacio, f\u00e1brica de tejidos de diferentes materiales, texturas y colores, y aportan un punto de singularidad al atrezzo de la protagonista. El ramo queda atado, igualmente, por hilo de algod\u00f3n amarillo. Precioso detalle, colorido y juvenil.<\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24707 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-62.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24708 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-63.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24706 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-69.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24699 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-73.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-73.jpg 850w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-73-600x400.jpg 600w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-73-300x200.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-73-768x512.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-73-450x300.jpg 450w\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La decoraci\u00f3n floral de las mesas se basa en hojas verdes tipo laurel y rosas en tonos claro y rosa, que combinan a la perfecci\u00f3n con la manteler\u00eda en tonos tierra y el mobiliarios en madera clara.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El novio acompa\u00f1a el estilismo de la novia con traje en azul oscuro, camisa blanca y detalles de tirantes y corbata oscura, a juego con los zapatos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El estilismo de la novia es obra de Javier Mir\u00f3n Peluqueros. Un recogido natural a un lado mediante un sencillo adorno floral en verdes y blanco, acorde con el vestido, y un cuidado pelo rizado, aporta frescura y naturalidad a la bella novia. El maquillaje, con sombras marrones y perfilado y pintalabios en los mismos tonos, aporta luz a la mirada y bronceada tez de nuestra novia.<\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24704 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-39.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24703 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-38.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24702 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-37.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24439 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices wedding - Perfect Venu\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-40.jpg\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24701 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Fabrica de tapices - Perfect Venue\" width=\"850\" height=\"567\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/fabrica-de-tapices-perfect-venue-75.jpg\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los espacios elegidos para las instant\u00e1neas, realizadas por el fot\u00f3grafo Mario Trueba, son, por un lado, el precioso jard\u00edn hist\u00f3rico de interpretaci\u00f3n textil, las escalinatas de acceso a la f\u00e1brica y su encantadora fachada de piedra y ladrillo y, por otro lado, diferentes espacios interiores, como son la sala Teniers, en la que se llev\u00f3 a cabo la ceremonia, bajo techos con vigas de madera, sobre delicadas alfombras y ante la grandeza de diferentes tapices hist\u00f3ricos, y la sala Goya, elegida en este caso para el banquete, decorada con diferentes \u00e1rboles, plantas y flores colgantes y con una perfecta luz tenue que aporta un ambiente agradable y acogedor al evento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nos encant\u00f3 poder formar parte del gran d\u00eda de Alejandro y Elianny y tener la oportunidad de disfrutar de toda la elegancia, encanto y esencia de Real F\u00e1brica de Tapices.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Esperamos os hayan gustado las fotograf\u00edas tomadas durante este bonito evento y os anim\u00e9is a visitar Real F\u00e1brica de Tapices para vuestra boda perfecta en Madrid.<\/span><\/p>\n<h3 style=\"text-align: justify;\">Wedding team:<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Espacio para boda:\u00a0<a href=\"https:\/\/perfectvenue.eu\/listings\/la-real-fabrica-de-tapices\/\">Real F\u00e1brica de Tapices<\/a> \/\/ Organizaci\u00f3n: <a href=\"https:\/\/nataliaortizevents.com\">Weddings and Events by Natalia Ortiz<\/a> \/\/\u00a0<\/span><span style=\"font-weight: 400;\">Fot\u00f3grafo: <a href=\"https:\/\/www.mariotrueba.net\/\">Mario Trueba<\/a><\/span><span style=\"font-weight: 400;\">\u00a0\/\/<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">MUAH: <a href=\"https:\/\/www.instagram.com\/javiermironpelu\/\">Javier Miron peluquero<\/a>\u00a0\/\/\u00a0<\/span><span style=\"font-weight: 400;\">Flores: <a href=\"https:\/\/monceau-fleurs.es\/\">Floristeria Monceau Fleurs<\/a> \/\/\u00a0<\/span><span style=\"font-weight: 400;\">Vestido de novia: <a href=\"https:\/\/www.jesuspeiro.com\/\">JESUS PEIRO<\/a><\/span><\/p>\n<p><\/p>\n<span class=\"tags-links\"><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/elegant-evenu-madrid\/\" rel=\"tag\">elegant evenu madrid<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/madrid-wedding\/\" rel=\"tag\">Madrid wedding<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/madrid-wedding-venue\/\" rel=\"tag\">Madrid wedding venue<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/real-fabrica-de-tapices\/\" rel=\"tag\">Real F\u00e1brica de Tapices<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/wedding-in-factory\/\" rel=\"tag\">wedding in factory<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/wedding-in-historical-place\/\" rel=\"tag\">wedding in historical place<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/%d1%81%d0%b2%d0%b0%d0%b4%d1%8c%d0%b1%d0%b0-%d0%b2-%d0%bc%d0%b0%d0%b4%d1%80%d0%b8%d0%b4%d0%b5\/\" rel=\"tag\">\u0441\u0432\u0430\u0434\u044c\u0431\u0430 \u0432 \u041c\u0430\u0434\u0440\u0438\u0434\u0435<\/a><\/span>","protected":false},"excerpt":{"rendered":"<p>Existen lugares con una esencia especial, una historia&#8230;, espacios singulares donde los eventos se vuelven m\u00e1gicos e irrepetibles. Real F\u00e1brica de Tapices es uno de esos lugares. Este espacio en pleno centro de Madrid, con m\u00e1s de 300 a\u00f1os de historia, nos ofrece un lugar \u00fanico donde llevar a cabo nuestra boda. Rodeados de verdaderas [&hellip;]<\/p>\n","protected":false},"author":83,"featured_media":24706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","footnotes":""},"categories":[945,943],"tags":[1331,1329,1330,1140,1120,1119,1332],"class_list":["post-23955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destination-bohemian-wedding","category-luxury-destination-wedding","tag-elegant-evenu-madrid","tag-madrid-wedding","tag-madrid-wedding-venue","tag-real-fabrica-de-tapices","tag-wedding-in-factory","tag-wedding-in-historical-place","tag-1332","post_region-spain"],"_links":{"self":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts\/23955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/comments?post=23955"}],"version-history":[{"count":0,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts\/23955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/media\/24706"}],"wp:attachment":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/media?parent=23955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/categories?post=23955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/tags?post=23955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}