{"id":25373,"date":"2019-12-05T15:26:13","date_gmt":"2019-12-05T14:26:13","guid":{"rendered":"https:\/\/perfectvenue.eu\/?p=25373"},"modified":"2019-12-09T15:27:09","modified_gmt":"2019-12-09T14:27:09","slug":"flowers-and-pastel-tones-a-romantic-wedding-at-lake-como","status":"publish","type":"post","link":"https:\/\/perfectvenue.eu\/es\/flowers-and-pastel-tones-a-romantic-wedding-at-lake-como\/","title":{"rendered":"Flores y tonos pastel: una rom\u00e1ntica boda en Lago Como"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Cuando Nadia y Marco comenzaron a planear su boda, sab\u00edan que quer\u00edan celebrarla en un lugar m\u00e1gico. Muchos de sus invitados viajaban a Italia desde varias partes del mundo, por tanto, quer\u00edan un sitio muy bien ubicado pero que a la vez fuera especial. Por eso, finalmente, se decidieron por una <strong>boda en Lago Como<\/strong>. La celebraci\u00f3n fue muy elegante y sencilla, los novios quer\u00edan realizar un peque\u00f1o homenaje a las relaciones modernas y las historias de amor aut\u00e9nticas.\u00a0<\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25381 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"565\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding7.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding7.jpg 850w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding7-600x399.jpg 600w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding7-300x199.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding7-768x510.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding7-450x299.jpg 450w\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25383 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"562\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding10.jpg\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25379 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"565\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding5.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding5.jpg 850w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding5-600x399.jpg 600w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding5-300x199.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding5-768x510.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding5-450x299.jpg 450w\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25380 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"565\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding6.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding6.jpg 850w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding6-600x399.jpg 600w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding6-300x199.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding6-768x510.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding6-450x299.jpg 450w\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25375 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"567\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding1.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding1.jpg 850w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding1-600x400.jpg 600w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding1-300x200.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding1-768x512.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding1-450x300.jpg 450w\"><\/span><\/p>\n<h3 style=\"text-align: justify;\">Vestido de dos piezas<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La novia estaba embarazada de siete meses cuando se celebr\u00f3 la boda, por tanto la b\u00fasqueda del vestido perfecto para su gran d\u00eda. Tras meses de b\u00fasqueda, encontr\u00f3 el dise\u00f1o perfecto: una creaci\u00f3n de dos piezas individuales hechas a manos de la firma Dyona Dresses. La novia qued\u00f3 completamente enamorada con el resultado.\u00a0<\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25385 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"562\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding12.jpg\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25388 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"562\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding15.jpg\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25384 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"562\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding11.jpg\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25378 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"567\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding4.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding4.jpg 850w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding4-600x400.jpg 600w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding4-300x200.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding4-768x512.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding4-450x300.jpg 450w\"><\/span><\/p>\n<h3 style=\"text-align: justify;\">Escenario floral<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Para la celebraci\u00f3n se cre\u00f3 un escenario de ensue\u00f1o, decorando todas las instalaciones con distintos tipos de flores como rosas o amapolas, y todas ellas, en colores verdes y suaves. Las mesas tambi\u00e9n se decoraron con arreglos florales, creando as\u00ed una atm\u00f3sfera de recepci\u00f3n en los invitados elegante e \u00edntima. Para cada detalle que se coloc\u00f3 en la celebraci\u00f3n se utiliz\u00f3 la paleta de <strong>colores pastel, concretamente, melocot\u00f3n y azul polvoriento.<\/strong><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25376 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"567\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding2.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding2.jpg 850w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding2-600x400.jpg 600w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding2-300x200.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding2-768x512.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding2-450x300.jpg 450w\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25374 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"563\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding19.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding19.jpg 850w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding19-600x397.jpg 600w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding19-300x199.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding19-768x509.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding19-450x298.jpg 450w\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25390 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"563\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding18.jpg\"><\/span><\/p>\n<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25392 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"850\" height=\"565\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/lakecomo-wedding8.jpg\"><\/span><\/p>\n<h3><span style=\"font-weight: 400;\">The wedding team:<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Fot\u00f3grafa: <\/span><a href=\"http:\/\/www.laurennicole.photo\/\"><span style=\"font-weight: 400;\">Lauren Nicole Photography<\/span><\/a><span style=\"font-weight: 400;\"> \/\/ Lugar: <\/span><a href=\"http:\/\/www.auradellago.com\/index.php\/en\/\"><span style=\"font-weight: 400;\">Aura del Lago<\/span><\/a><span style=\"font-weight: 400;\">, Limonta, Lake Como, Italy \/\/ Wedding Planner: <\/span><a href=\"http:\/\/www.benevent.it\/\"><span style=\"font-weight: 400;\">Benevent Planner<\/span><\/a><span style=\"font-weight: 400;\"> \/\/ Flores: <\/span><a href=\"https:\/\/www.evelinaflorence.com\/\"><span style=\"font-weight: 400;\">Evelina Florence Flowers<\/span><\/a><span style=\"font-weight: 400;\"> \/\/ Vestido: <\/span><a href=\"http:\/\/www.dyona.sk\/\"><span style=\"font-weight: 400;\">Dyona Dresses<\/span><\/a><span style=\"font-weight: 400;\"> \/\/ Peluquer\u00eda: <\/span><a href=\"https:\/\/www.guineverevines.com\/sense-and-sensibility\"><span style=\"font-weight: 400;\">Guinevere Vines Headpiece<\/span><\/a><span style=\"font-weight: 400;\"> \/\/ Zapatos de novia: <\/span><a href=\"https:\/\/www.prada.com\/us\/en.html\"><span style=\"font-weight: 400;\">Prada<\/span><\/a><span style=\"font-weight: 400;\"> \/\/ Catering: <\/span><a href=\"https:\/\/www.classeventi.it\/\"><span style=\"font-weight: 400;\">Class<\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<span class=\"tags-links\"><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/boda-en-italia\/\" rel=\"tag\">boda en Italia<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/boda-en-lago-como\/\" rel=\"tag\">boda en lago como<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/lake-como\/\" rel=\"tag\">Lake Como<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/wedding-in-lake-como\/\" rel=\"tag\">wedding in lake como<\/a><\/span>","protected":false},"excerpt":{"rendered":"<p>Cuando Nadia y Marco comenzaron a planear su boda, sab\u00edan que quer\u00edan celebrarla en un lugar m\u00e1gico. Muchos de sus invitados viajaban a Italia desde varias partes del mundo, por tanto, quer\u00edan un sitio muy bien ubicado pero que a la vez fuera especial. Por eso, finalmente, se decidieron por una boda en Lago Como. [&hellip;]<\/p>\n","protected":false},"author":86,"featured_media":25386,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","footnotes":""},"categories":[945,943],"tags":[671,1365,827,755],"class_list":["post-25373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destination-bohemian-wedding","category-luxury-destination-wedding","tag-boda-en-italia","tag-boda-en-lago-como","tag-lake-como","tag-wedding-in-lake-como","post_region-italy"],"_links":{"self":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts\/25373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/comments?post=25373"}],"version-history":[{"count":0,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts\/25373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/media\/25386"}],"wp:attachment":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/media?parent=25373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/categories?post=25373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/tags?post=25373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}