{"id":32785,"date":"2022-10-19T12:17:00","date_gmt":"2022-10-19T11:17:00","guid":{"rendered":"https:\/\/perfectvenue.eu\/?p=32785"},"modified":"2023-11-03T10:51:04","modified_gmt":"2023-11-03T09:51:04","slug":"20-espacios-donde-una-celebracion-boda-segovia-ensueno","status":"publish","type":"post","link":"https:\/\/perfectvenue.eu\/es\/20-espacios-donde-una-celebracion-boda-segovia-ensueno\/","title":{"rendered":"20 espacios donde hacer una celebraci\u00f3n de\u00a0 boda en Segovia de ensue\u00f1o\u00a0"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Hoy os recomendamos un lugar lleno de magia e historia: Segovia. Sus encantos, el clima y la gran cantidad de espacios donde decir \u00abs\u00ed,quiero\u00bb han atra\u00eddo a muchas parejas a esta provincia.Ya sea que dese\u00e9is vivir vuestro propio cuento de hadas o simplemente est\u00e9is buscando el lugar perfecto para celebrar vuestra boda, aqu\u00ed os dejamos algunas fincas bastante recomendadas que son perfectas para la <\/span><b>celebraci\u00f3n de bodas en Segovia.<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Adem\u00e1s, las fincas de bodas ofrecen dos de las mejores especialidades culinarias de Espa\u00f1a, el lechazo y el cochinillo asados \u200b\u200ben el tradicional horno de le\u00f1a. Otros de sus platos principales son la trucha de Segovia, las perdices a la Segoviana, las setas y el conejo.\u00a0\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Los Claustros de Ayll\u00f3n<\/span><\/h3>\n<figure id=\"attachment_32066\" aria-describedby=\"caption-attachment-32066\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32066 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Los Claustros de Ayll\u00f3n\" width=\"700\" height=\"498\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/LOS_CLAUSTROS_DE_AYLL\u00d3N1.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/LOS_CLAUSTROS_DE_AYLL\u00d3N1.jpg 700w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/LOS_CLAUSTROS_DE_AYLL\u00d3N1-300x213.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/LOS_CLAUSTROS_DE_AYLL\u00d3N1-450x320.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/LOS_CLAUSTROS_DE_AYLL\u00d3N1-600x427.jpg 600w\"><figcaption id=\"caption-attachment-32066\" class=\"wp-caption-text\">Los Claustros de Ayll\u00f3n<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Es una de las fincas m\u00e1s \u00fanicas y exclusivas de Segovia y ocupa una superficie de 35.000 m\u00b2. Podr\u00e9is celebrar vuestra boda en un entorno especial con m\u00e1s de 800 a\u00f1os de historia donde dispondr\u00e9is de un lugar para cada momento. Una ceremonia civil en las ruinas de la iglesia cuidadas al m\u00ednimo detalle, un banquete en el sal\u00f3n de cristal o un c\u00f3ctel en el estanque natural. Dispone de un hotel con 19 habitaciones exclusivas para los invitados. La cocina la prepara Vatelia Catering, con m\u00e1s de 10 a\u00f1os de experiencia en el oficio. En los claustros se encuentran las ruinas del antiguo convento franciscano, que han sido cuidadosamente restauradas y conservadas en su aspecto original. Tambi\u00e9n cuenta con un espacio natural lleno de jardines y zonas verdes. Se encuentra adem\u00e1s a 126km del aeropuerto de Madrid y a 98km del centro de Segovia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Precio del men\u00fa: desde 141\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Caser\u00edo de Lobones<\/span><\/h3>\n<figure id=\"attachment_32787\" aria-describedby=\"caption-attachment-32787\" style=\"width: 695px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32787 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Caser\u00edo de Lobones - Perfect Venue\" width=\"695\" height=\"429\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Caser\u00edo-de-Lobones.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Caser\u00edo-de-Lobones.jpg 695w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/Caser\u00edo-de-Lobones-300x185.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/Caser\u00edo-de-Lobones-450x278.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/Caser\u00edo-de-Lobones-600x370.jpg 600w\"><figcaption id=\"caption-attachment-32787\" class=\"wp-caption-text\">Caser\u00edo de Lobones<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Este precioso cortijo del siglo XVII se encuentra en plena naturaleza y en una ubicaci\u00f3n privilegiada ya que est\u00e1 a tan solo 9 km de Segovia y 90 km de Madrid. Adem\u00e1s, la finca cuenta con la categor\u00eda de Posada Real, la m\u00e1xima calificaci\u00f3n que otorga la Junta de Castilla y Le\u00f3n por cumplir con los est\u00e1ndares tur\u00edsticos del establecimiento hotelero. Cuenta con m\u00faltiples espacios multifuncionales, tanto en el exterior como en el interior, as\u00ed como un hotel exclusivo para los invitados, un jard\u00edn principal, sala con capacidad para 270 personas, zonas exteriores y un gran parking. Tienen una amplia experiencia en la organizaci\u00f3n de bodas y aparte de la gesti\u00f3n integral de los eventos, os ayudan a personalizarlo a vuestro gusto aportando ideas, escuchando propuestas que hag\u00e1is e impulsando iniciativas de mejora. Adem\u00e1s cuenta con otros servicios como la celebraci\u00f3n de ceremonias civiles, capilla dentro de la finca, mayordomos y servicio de transporte<\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alquiler: desde 4.840\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Finca los Jazmines<\/span><\/h3>\n<figure id=\"attachment_32788\" aria-describedby=\"caption-attachment-32788\" style=\"width: 977px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32788 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Finca los Jazmines - Perfect Venue\" width=\"977\" height=\"616\" sizes=\"auto, (max-width: 977px) 100vw, 977px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Finca-los-Jazmines.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Finca-los-Jazmines.jpg 977w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/Finca-los-Jazmines-300x189.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/Finca-los-Jazmines-768x484.jpg 768w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/Finca-los-Jazmines-450x284.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/Finca-los-Jazmines-600x378.jpg 600w\"><figcaption id=\"caption-attachment-32788\" class=\"wp-caption-text\">Finca los Jazmines<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">E<\/span><span style=\"font-weight: 400;\">st\u00e1 situado en pleno centro de Segovia, a tan solo 5 minutos del famoso Puente de Segovia, al lado del Hotel C\u00e1ndido, con espectaculares vistas al Alc\u00e1zar en el horizonte y a 1 hora del aeropuerto de Adolfo Suarez. Es una finca nueva pero con m\u00e1s de 30 a\u00f1os de experiencia organizando eventos. Tambi\u00e9n cuenta con un hotel con vistas espectaculares para los invitados y la posibilidad de bailar en el jard\u00edn exterior. Sin duda una de las mejores opciones en cuanto a calidad-precio de toda Segovia, combinando una ubicaci\u00f3n y experiencia privilegiadas.\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">La estaci\u00f3n<\/span><\/h3>\n<figure id=\"attachment_32789\" aria-describedby=\"caption-attachment-32789\" style=\"width: 881px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32789 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"La estaci\u00f3n\" width=\"881\" height=\"578\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/La-estaci\u00f3n-1.jpg\"><figcaption id=\"caption-attachment-32789\" class=\"wp-caption-text\">La estaci\u00f3n<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si busc\u00e1is un lugar vers\u00e1til, este es el vuestro. Se trata de una antigua f\u00e1brica de ladrillos situada en Otero de Herreros, a 20 minutos de Segovia y a algo menos de 1 hora del aeropuerto de Madrid Barajas, perfecta para bodas con mucha personalidad. En La Estaci\u00f3n vuestra imaginaci\u00f3n es la que pone los l\u00edmites y podr\u00e9is hacer de este, un d\u00eda 100% dise\u00f1ado por vosotros. Una boda a medida en la cual el personal os ayudar\u00e1 en todo lo que necesit\u00e9is para decorar y personalizar el espacio a vuestro gusto. \u00bfMatrimonio religioso o civil? Pod\u00e9is tener ambos porque la finca tiene una iglesia y las bodas civiles se pueden celebrar al aire libre en el patio principal o en la sala de suelo hidr\u00e1ulico, perfecta para las celebraciones de oto\u00f1o o invierno. Y tambi\u00e9n cuenta con distintas salas y patio exterior e interior perfectos para los diferentes momentos del evento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Precios del men\u00fa: desde 155\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Palacio de Esquileo<\/span><\/h3>\n<figure id=\"attachment_32069\" aria-describedby=\"caption-attachment-32069\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32069 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Palacio de Esquileo - Perfect Venue\" width=\"700\" height=\"467\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/PALACIO_DE_ESQUILEO1.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/PALACIO_DE_ESQUILEO1.jpg 700w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/PALACIO_DE_ESQUILEO1-300x200.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/PALACIO_DE_ESQUILEO1-450x300.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/PALACIO_DE_ESQUILEO1-600x400.jpg 600w\"><figcaption id=\"caption-attachment-32069\" class=\"wp-caption-text\">Palacio de Esquileo<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Se encuentra cerca de Riaza en Sotos de Sepulveda, enclavado en un paraje natural, apto para albergar a vuestros invitados. Se ha restaurado un antiguo palacio con toda clase de detalles, un hermoso jard\u00edn y un estanque natural. El Palacio de Esquileo acoge tanto bodas \u00edntimas como bodas de hasta 300 personas, donde se puede celebrar la ceremonia civil al aire libre, en una sala bonita y cuidada o en el interior seg\u00fan un plan B, si las condiciones meteorol\u00f3gicas no lo permiten. Por el contrario, si vuestra boda va a ser de car\u00e1cter religioso, hay una serie de iglesias a pocos minutos del palacio, como la Iglesia de Durat\u00f3n o la Iglesia Rom\u00e1nica de Soto de Sepulveda. Cuentan con cocina propia y en ella se combina la cocina internacional con los asados cl\u00e1sicos de ceviche de trucha o cochinillo. Esta propiedad para la <\/span><b>celebraci\u00f3n de bodas en Segovia<\/b><span style=\"font-weight: 400;\"> tiene una serie de ofertas tanto para bodas de invierno como de verano bastante recomendables.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Men\u00fas: desde 80\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Finca el Rancho de la Aldeg\u00fcela<\/span><\/h3>\n<figure id=\"attachment_32790\" aria-describedby=\"caption-attachment-32790\" style=\"width: 1036px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32790 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Finca el Rancho de la Aldeg\u00fcela - Perfect Venue\" width=\"1036\" height=\"608\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Finca-el-Rancho-de-la-Aldeg\u00fcela.jpg\"><figcaption id=\"caption-attachment-32790\" class=\"wp-caption-text\">Finca el Rancho de la Aldeg\u00fcela<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Situado en Torrecaballeros, a 14 km del centro de Segovia y 114km del aeropuerto de Madrid, es una de las fincas m\u00e1s antiguas de la ciudad y cuenta con una gran experiencia en el sector.\u00a0 Dispone de varios salones de bodas, hotel para invitados, jardines y piscina. Si no os importa compartir la finca con otras bodas y quer\u00e9is una a un precio asequible pero con la experiencia y calidad excelentes de sus cocineros en hacer cordero y cochinillo asado, es una de las mejores opciones. Con un precio bastante econ\u00f3mico en el men\u00fa de bodas, ofrece a los novios una suite para el d\u00eda de la boda en el Hotel SPA del Rancho con desayuno y cava incluido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Men\u00fas: desde 55\u20ac<\/span><\/p>\n<h3><a href=\"https:\/\/perfectvenue.es\/es\/listings\/finca-aldeallana\/\"><span style=\"font-weight: 400;\">Finca Aldeallana<\/span><\/a><\/h3>\n<figure id=\"attachment_32073\" aria-describedby=\"caption-attachment-32073\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32073 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Finca Aldeallana - Perfect Venue\" width=\"700\" height=\"466\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_ALDEALLANA1.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_ALDEALLANA1.jpg 700w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_ALDEALLANA1-300x200.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_ALDEALLANA1-450x300.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_ALDEALLANA1-600x399.jpg 600w\"><figcaption id=\"caption-attachment-32073\" class=\"wp-caption-text\">Finca Aldeallana<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A tan solo 75 km de Madrid y 20 km de Segovia, Aldeallana es el lugar perfecto para celebrar bodas civiles y religiosas dentro de la propiedad, ya que la Iglesia de Santa Eulalia de M\u00e9rida se encuentra a solo 3 km. El cuidado, la atenci\u00f3n al detalle, el buen gusto y la perfecci\u00f3n son el lema del equipo de este hotel, donde podr\u00e9is disfrutar de una boda de lujo con todo el encanto del campo. Adem\u00e1s, la finca dispone de cocina propia con servicio de catering Ciboulette que asegura un servicio impecable y os lo hace todo m\u00e1s f\u00e1cil.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">De Natura<\/span><\/h3>\n<figure id=\"attachment_32074\" aria-describedby=\"caption-attachment-32074\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32074 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"De Natura - Perfect Venue\" width=\"700\" height=\"464\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/DE_NATURA_PEDRAZA1.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/DE_NATURA_PEDRAZA1.jpg 700w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/DE_NATURA_PEDRAZA1-300x199.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/DE_NATURA_PEDRAZA1-450x298.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/DE_NATURA_PEDRAZA1-600x398.jpg 600w\"><figcaption id=\"caption-attachment-32074\" class=\"wp-caption-text\">De Natura<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si hab\u00e9is estado alguna vez en Pedraza, seguro que habr\u00e9is pensado en casaros all\u00ed. Cualquiera que ponga un pie en este lugar queda atrapado por su belleza medieval, perfecto para una boda de cuento de hadas. Est\u00e1 ubicado en un palacio del siglo XVII que fue restaurado en la d\u00e9cada de los 70 por el decorador Paco Mu\u00f1oz. Actualmente tiene tres plantas di\u00e1fanas, de casi 1.000 metros de altura, y un jard\u00edn con unas vistas espectaculares. Su estructura de madera vista, chimenea y suelos de barro lo convierten en el lugar perfecto para una boda familiar y acogedora sin renunciar al encanto. Adem\u00e1s, Samantha Vallejo-Nagera y Sabina Deroned, cuidar\u00e1n cada detalle de vuestra boda, dando un toque especial a vuestro gran d\u00eda. Pero aunque est\u00e9 un poco alejado del aeropuerto (a 113km) y a 40km de Segovia, sin duda merece la pena plantearse la idea de celebrar all\u00ed vuestra boda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Alquiler: desde 3.500\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Finca Lasmargas<\/span><\/h3>\n<figure id=\"attachment_32075\" aria-describedby=\"caption-attachment-32075\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32075 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Finca Lasmargas - Perfect Venue\" width=\"700\" height=\"471\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_LASMARGAS1.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_LASMARGAS1.jpg 700w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_LASMARGAS1-300x202.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_LASMARGAS1-450x303.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_LASMARGAS1-600x404.jpg 600w\"><figcaption id=\"caption-attachment-32075\" class=\"wp-caption-text\">Finca Lasmargas<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Este antiguo caser\u00edo reconvertido en un hotel con mucho encanto se encuentra a 7 km de Segovia y 90km del aeropuerto de Madrid. La estructura del edificio data del siglo XVII y cuenta con dos grandes salones, un patio central y maravillosos jardines, lo que lo hace perfecto para albergar cualquier evento. La decoraci\u00f3n y el gusto sofisticado son solo algunos de los factores que hacen que muchas parejas elijan este lugar para su boda. Su dilatada experiencia en la organizaci\u00f3n de bodas es un plus ya que ponen a vuestra disposici\u00f3n un equipo de profesionales para que todo salga seg\u00fan vuestras expectativas.\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Abad\u00eda de P\u00e1rraces<\/span><\/h3>\n<figure id=\"attachment_32068\" aria-describedby=\"caption-attachment-32068\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32068 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Abad\u00eda de P\u00e1rraces - Perfect Venue\" width=\"700\" height=\"469\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/ABAD\u00cdA_DE_P\u00c1RRACES1.png\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/ABAD\u00cdA_DE_P\u00c1RRACES1.png 700w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/ABAD\u00cdA_DE_P\u00c1RRACES1-300x201.png 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/ABAD\u00cdA_DE_P\u00c1RRACES1-450x302.png 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/ABAD\u00cdA_DE_P\u00c1RRACES1-600x402.png 600w\"><figcaption id=\"caption-attachment-32068\" class=\"wp-caption-text\">Abad\u00eda de P\u00e1rraces<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Otro lugar \u00fanico donde <\/span><b>celebrar bodas en Segovia<\/b><span style=\"font-weight: 400;\">. En particular, se trata de un monasterio que data del siglo XVI, el cual ha sido clasificado como una reliquia cultural. Se encuentra en Bercial, a tan solo 20 minutos de Segovia y a 50 minutos de Madrid. Rodeado de pintorescos jardines, ofrece excelentes vistas de las monta\u00f1as. Lo m\u00e1s sobresaliente del monasterio, sin embargo, son sus dos salones, perfectos para celebrar bodas (por muchos invitados que haya). Para banquetes de boda en el interior, el establecimiento dispone de una sala para m\u00e1s de 500 personas, decorada con un estilo renacentista de finales del siglo XVI. Una elecci\u00f3n con encanto, perfecta para bodas diferentes donde tradici\u00f3n y modernidad van de la mano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Men\u00fas: desde 115\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Finca de Duque<\/span><\/h3>\n<figure id=\"attachment_32076\" aria-describedby=\"caption-attachment-32076\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32076 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Finca de Duque - Perfect Venue\" width=\"700\" height=\"469\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/LA_FINCA_DEL_DUQUE1.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/LA_FINCA_DEL_DUQUE1.jpg 700w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/LA_FINCA_DEL_DUQUE1-300x201.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/LA_FINCA_DEL_DUQUE1-450x302.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/LA_FINCA_DEL_DUQUE1-600x402.jpg 600w\"><figcaption id=\"caption-attachment-32076\" class=\"wp-caption-text\">Finca de Duque<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Es un conjunto vers\u00e1til que est\u00e1 a escasos kil\u00f3metros de Segovia. Perfecto para bodas tanto civiles como religiosas, rodeado de un jard\u00edn de 1500 metros cuadrados. Tambi\u00e9n cuenta con cocina propia dirigida por Juli\u00e1n Duque. En este caso no estamos hablando de un edificio cargado de historia como en los casos anteriores, sino de modernas comodidades equipadas para que vuestro d\u00eda sea absolutamente perfecto. Una finca perfecta donde poder celebrar la boda de vuestros sue\u00f1os personalizando cada detalle y jugando con el espacio y las opciones.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Finca Prados Riveros<\/span><\/h3>\n<figure id=\"attachment_32077\" aria-describedby=\"caption-attachment-32077\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32077 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Finca Prados Riveros - Perfect Venue\" width=\"700\" height=\"467\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_PRADOS_RIVEROS1.jpg\" data-srcset=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_PRADOS_RIVEROS1.jpg 700w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_PRADOS_RIVEROS1-300x200.jpg 300w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_PRADOS_RIVEROS1-450x300.jpg 450w, https:\/\/perfectvenue.eu\/wp-content\/uploads\/FINCA_PRADOS_RIVEROS1-600x400.jpg 600w\"><figcaption id=\"caption-attachment-32077\" class=\"wp-caption-text\">Finca Prados Riveros<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En Madrid, pero muy cerca de Segovia y a 1 hora del aeropuerto de Madrid-Barajas, se encuentra Prados Riveros, una finca de 12 hect\u00e1reas situada en el Parque Natural de Pe\u00f1alara. Reinventa la idea de boda campestre, logrando celebrar unas bodas \u00fanicas, personalizadas y cautivadoras. Un lugar id\u00edlico entre pastizales, pinares y encinas. El recinto es apto tanto para bodas civiles, que pueden celebrarse en las instalaciones del hotel, como para bodas religiosas, ya que muy cerca se encuentra el Real Monasterio de Santa Mar\u00eda del Paular. Sin duda una recomendaci\u00f3n para todos aquellos que buscan algo diferente en una versi\u00f3n r\u00fastica y con estilo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Men\u00fas: desde 100\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Villa \u00c1ngeles<\/span><\/h3>\n<figure id=\"attachment_32791\" aria-describedby=\"caption-attachment-32791\" style=\"width: 906px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32791 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Villa \u00c1ngeles - Perfect Venue\" width=\"906\" height=\"359\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Villa-\u00c1ngeles.jpg\"><figcaption id=\"caption-attachment-32791\" class=\"wp-caption-text\">Villa \u00c1ngeles<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Se encuentra en el campo de golf Asr, inaugurado en mayo de 2010, enclavado en el entorno natural de la Sierra de Guadarrama, a 25 minutos de Segovia y 1 hora del aeropuerto.\u00a0 Con un dise\u00f1o impactante, se caracteriza por integrarse con el entorno natural. El espectacular encinar, salpicado de espectaculares formaciones rocosas, corta el profundo meandro del r\u00edo Moros. El pabell\u00f3n, ubicado en la casa club del campo de golf, es el lugar perfecto para la celebraci\u00f3n de la boda, con una capacidad para acoger hasta 500 personas y unos grandes ventanales que dejan pasar la luz, creando una atm\u00f3sfera inigualable. Su ubicaci\u00f3n privilegiada le permite convertirse en el mirador perfecto para contemplar el espect\u00e1culo natural que le rodea.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Precio: Desde 300\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">La Portada de Mediod\u00eda<\/span><\/h3>\n<figure id=\"attachment_32792\" aria-describedby=\"caption-attachment-32792\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32792 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"La Portada de Mediod\u00eda - Perfect Venue\" width=\"1280\" height=\"625\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/La-Portada-de-Mediod\u00eda.jpg\"><figcaption id=\"caption-attachment-32792\" class=\"wp-caption-text\">La Portada de Mediod\u00eda<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La antigua casa de correos del siglo XVI goza de una ubicaci\u00f3n privilegiada custodiada por la iglesia rom\u00e1nica de San Nicol\u00e1s de Bari a la entrada de Torrecaballeros, una localidad en plena Sierra de Castilla, a pocos minutos de Segovia y a algo m\u00e1s de cuarenta minutos de Madrid. El comedor principal con su original terraza abierta de madera es el escenario perfecto para una fiesta hist\u00f3rica. Adem\u00e1s, tiene una capacidad para acoger hasta 200 invitados y el ambiente se vuelve incre\u00edblemente acogedor gracias a la iluminaci\u00f3n indirecta con toques c\u00e1lidos y un mont\u00f3n de detalles dignos de presentar. Velas, flores frescas, obras de arte, un maravilloso jard\u00edn, etc. Un recuerdo inolvidable para un d\u00eda tan especial.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Men\u00fas: desde 70\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">La Tejera de Fausto<\/span><\/h3>\n<figure id=\"attachment_32793\" aria-describedby=\"caption-attachment-32793\" style=\"width: 1043px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32793 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"La Tejera de Fausto - Perfect Venue\" width=\"1043\" height=\"654\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/La-Tejera-de-Fausto.jpg\"><figcaption id=\"caption-attachment-32793\" class=\"wp-caption-text\">La Tejera de Fausto<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Este hermoso restaurante goza de una ubicaci\u00f3n pintoresca, brindando el escenario perfecto para celebrar vuestro gran d\u00eda. Cuenta con un gran sal\u00f3n cubierto y elegantes carpas en el jard\u00edn con una capacidad m\u00e1xima de 100 y 250 comensales respectivamente. Ambos espacios son hermosos, ya sea por su cuidada decoraci\u00f3n con toques r\u00fasticos y elegantes o por la majestuosidad de la vegetaci\u00f3n y los distintos rincones del exterior.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Men\u00fas: desde 79\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">El Mirador del Botero<\/span><\/h3>\n<figure id=\"attachment_32794\" aria-describedby=\"caption-attachment-32794\" style=\"width: 772px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32794 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"El Mirador del Botero - Perfect Venue\" width=\"772\" height=\"513\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/El-Mirador-del-Botero.jpg\"><figcaption id=\"caption-attachment-32794\" class=\"wp-caption-text\">El Mirador del Botero<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si quer\u00e9is celebrar all\u00ed mismo una ceremonia civil\u2026 Un arco de hierro, el sonido del agua de la fuente, un esbelto arco de piedra, la luz que se filtra entre los huecos del empedrado y los \u00e1rboles har\u00e1n que la ceremonia tenga un toque de romanticismo \u00fanico. Y adem\u00e1s podr\u00e9is elegir hacerla en el exterior, en un jard\u00edn de 20,000 metros cuadrados que os invita a pasearlo, disfrutar de c\u00f3cteles en la terraza y hacer la sobremesa en la zona de sof\u00e1s. En cambio, si quer\u00e9is una boda interior o el tiempo es lo que os permite, tendr\u00e9is una amplia sala de cristal que ofrece unas vistas espectaculares de la Sierra de Aion, la ciudad y el jard\u00edn con techos altos con vigas, una pista de baile y un amplio bar con rinc\u00f3n de mojitos. Tampoco os tendr\u00e9is que preocupar por la ubicaci\u00f3n, ya que se encuentra a poco m\u00e1s de 1 hora de la ciudad de Segovia y del aeropuerto de Madrid.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Precio: desde 90\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Estancia Macondo<\/span><\/h3>\n<figure id=\"attachment_32795\" aria-describedby=\"caption-attachment-32795\" style=\"width: 1103px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32795 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Estancia Macondo - Perfect Venue\" width=\"1103\" height=\"605\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Estancia-Macondo.jpg\"><figcaption id=\"caption-attachment-32795\" class=\"wp-caption-text\">Estancia Macondo<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Es un centro de turismo rural, creado y adaptado para la celebraci\u00f3n de eventos. Si est\u00e1is buscando un lugar donde la naturaleza se mezcle con un ambiente c\u00f3modo y vers\u00e1til, esta finca es una muy buena opci\u00f3n. Podr\u00e9is disfrutar de la fiesta tanto al aire libre como en el interior. El d\u00eda de vuestra boda dispondr\u00e9is de una serie de espacios donde podr\u00e9is celebrar los distintos momentos del evento y los cuales tienen una capacidad de entre 20 y 110 personas. El Lounge, que un espacio acogedor donde se dispondr\u00e1n las mesas para que disfruteis de la fiesta, un jard\u00edn con piscina perfecto tanto para un c\u00f3ctel de bienvenida como para una fiesta al aire libre y por \u00faltimo un espacio relax, donde os podr\u00e9is relajar con vuestros amigos y familiares mientras tom\u00e1is una copa. Adem\u00e1s est\u00e1 a tan solo 20 minutos de la capital y a cerca de 1h del aeropuerto de Adolfo Su\u00e1rez<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Men\u00fas: desde 45\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Molino de la Ferrer\u00eda<\/span><\/h3>\n<figure id=\"attachment_32796\" aria-describedby=\"caption-attachment-32796\" style=\"width: 1239px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32796 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Molino de la Ferrer\u00eda - Perfect Venue\" width=\"1239\" height=\"660\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Molino-de-la-Ferrer\u00eda.jpg\"><figcaption id=\"caption-attachment-32796\" class=\"wp-caption-text\">Molino de la Ferrer\u00eda<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Se encuentra situado en el campo, rodeado de robles, en un espacio precioso a 10km de la ciudad. El Molino de la Ferrer\u00eda ofrece una tranquilidad absoluta y una calidad inmejorable, combinando la tradici\u00f3n rural con un trato del personal inmejorable. Tambi\u00e9n cuenta con una sala de estar con muebles antiguos de f\u00e1brica, chimenea y ventana con vista al jard\u00edn, donde tambi\u00e9n hay mesas por si prefer\u00eds celebrar el evento en el exterior.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Precio: desde 40\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Parador del Durat\u00f3n<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Se trata de un impresionante edificio de piedra del siglo XVI, totalmente restaurado con mucho encanto, ubicado a orillas del r\u00edo Durat\u00f3n (a tan solo 8 minutos del centro de Segovia y 1h del aeropuerto de madrid) con una superficie de 60.000 metros cuadrados, donde se pueden admirar los extensos y bien cuidados jardines con estanques y \u00e1rboles centenarios, terrazas exteriores y una piscina exterior de temporada. El equipo del Parador del Durat\u00f3n y Convento de San Francisco usar\u00e1 sus espacios tanto exteriores como interiores para que celebr\u00e9is vuestro gran d\u00eda. Impresionantes salones y jardines al aire libre con diferentes \u00e1reas para cada etapa del evento har\u00e1n que la celebraci\u00f3n sea \u00fanica e inolvidable.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Alquiler: desde 127,50\u20ac<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Restaurante Hotel Florida<\/span><\/h3>\n<figure id=\"attachment_32798\" aria-describedby=\"caption-attachment-32798\" style=\"width: 802px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32798 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Restaurante Hotel Florida - Perfect Venue\" width=\"802\" height=\"525\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/Restaurante-Hotel-Florida.jpg\"><figcaption id=\"caption-attachment-32798\" class=\"wp-caption-text\">Restaurante Hotel Florida<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Este encantador hotel restaurante combina el arte y la naturaleza para brindaros un ambiente \u00fanico, c\u00e1lido y acogedor con la paz y la privacidad que seguro que busc\u00e1is para vuestro gran d\u00eda. Tiene una ubicaci\u00f3n privilegiada, en Cu\u00e9llar, rodeada de perfectos parajes naturales y a tan solo 30 minutos del centro de la ciudad . Disfrutar\u00e9is tanto del hermoso jard\u00edn como del sal\u00f3n. Cuenta con m\u00faltiples salas y salones con toda la equipaci\u00f3n necesaria para hacer una celebraci\u00f3n por todo lo alto. Combina el buen gusto con un ambiente c\u00e1lido y acogedor que invita a recorrer todos sus rincones. Posee un comedor privado con una capacidad de hasta 30 personas; un comedor principal para 75 personas; el sal\u00f3n para banquetes, que acoge hasta 450 invitados; la discoteca, donde podr\u00e9is celebrar la fiesta posterior al banquete y por \u00faltimo el jard\u00edn, un lugar id\u00edlico donde disfrutar de un c\u00f3ctel o aperitivo, rodeado de hermosas vistas y vegetaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Estos son solo algunos de los espacios m\u00e1s impresionantes donde se pueden <\/span><b>celebrar bodas en Segovia, <\/b><span style=\"font-weight: 400;\">pero si os ha llamado la atenci\u00f3n alguno en particular s\u00f3lo tendr\u00e9is que poneros en contacto con el espacio y pedir m\u00e1s informaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si quer\u00e9is saber m\u00e1s sobre bodas, no dud\u00e9is en visitar <\/span><a href=\"https:\/\/perfectvenue.es\/es\/2022\/05\/19\/cuales-son-los-profesionales-que-se-necesitan-en-una-boda-y-su-organizacion\/\"><span style=\"font-weight: 400;\">profesionales que se necesitan en una boda y su organizaci\u00f3n<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0 \u00a1Esperamos haberos ayudado!\u00a0<\/span><\/p>\n<p><\/p>\n<span class=\"tags-links\"><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/boda\/\" rel=\"tag\">boda<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/boda-en-espana\/\" rel=\"tag\">boda en espa\u00f1a<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/celebracion-de-bodas-segovia\/\" rel=\"tag\">celebraci\u00f3n de bodas Segovia<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/destination-wedding\/\" rel=\"tag\">destination wedding<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/venue-for-weddings\/\" rel=\"tag\">venue for weddings<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/wedding-in-spain\/\" rel=\"tag\">wedding in spain<\/a><a href=\"https:\/\/perfectvenue.eu\/es\/tag\/wedding-venue\/\" rel=\"tag\">wedding venue<\/a><\/span>","protected":false},"excerpt":{"rendered":"<p>Celebraci\u00f3n de bodas Segovia. Adem\u00e1s, las fincas de bodas ofrecen dos de las mejores especialidades culinarias de Espa\u00f1a\u200b.<\/p>\n","protected":false},"author":1,"featured_media":32071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","footnotes":""},"categories":[945],"tags":[676,413,2684,495,474,354,332],"class_list":["post-32785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destination-bohemian-wedding","tag-boda","tag-boda-en-espana","tag-celebracion-de-bodas-segovia","tag-destination-wedding","tag-venue-for-weddings","tag-wedding-in-spain","tag-wedding-venue","post_region-espana","post_region-segovia"],"_links":{"self":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts\/32785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/comments?post=32785"}],"version-history":[{"count":0,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/posts\/32785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/media\/32071"}],"wp:attachment":[{"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/media?parent=32785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/categories?post=32785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perfectvenue.eu\/es\/wp-json\/wp\/v2\/tags?post=32785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}