{"id":28816,"date":"2020-11-14T15:03:55","date_gmt":"2020-11-14T14:03:55","guid":{"rendered":"https:\/\/perfectvenue.eu\/?p=28816"},"modified":"2023-06-09T09:58:18","modified_gmt":"2023-06-09T08:58:18","slug":"megan-and-kevins-love-story","status":"publish","type":"post","link":"https:\/\/perfectvenue.eu\/fr\/megan-and-kevins-love-story\/","title":{"rendered":"L&rsquo;histoire d&rsquo;amour de Megan et Kevin"},"content":{"rendered":"<p><\/p>\n<h2 style=\"text-align: justify;\">Comment nous nous sommes rencontr\u00e9s<\/h2>\n<p>Kevin et moi nous sommes rencontr\u00e9s au lyc\u00e9e, dans notre quartier du Texas. J&rsquo;avais entendu parler de lui \u00e0 l&rsquo;\u00e9cole parce qu&rsquo;il \u00e9tait le seul \u00e0 porter une veste sur le th\u00e8me de Harry Potter et que j&rsquo;ADORE tout ce qui a trait \u00e0 Harry Potter. Un jour, nous avons eu la chance de nous rencontrer et nous avons \u00e9chang\u00e9 quelques mots, puis nous sommes partis dans une autre direction. Le lendemain, nous nous sommes crois\u00e9s dans le couloir, ce qui a marqu\u00e9 le d\u00e9but d&rsquo;une amiti\u00e9 incroyable &#8211; la v\u00e9rit\u00e9 est l\u00e0, nous \u00e9tions exclusivement de vieux copains pendant un long moment ! \u00c0 un moment donn\u00e9, sorti de nulle part, Kevin a d\u00e9cid\u00e9 de m&rsquo;inviter \u00e0 sortir en ville et j&rsquo;ai r\u00e9agi en disant : \u00ab\u00a0D&rsquo;accord, mais \u00e0 condition que tu acceptes que je sois maladroite\u00a0\u00bb. Je suppose que cela ne l&rsquo;a pas d\u00e9rang\u00e9 !<\/p>\n<p>Nous sommes sortis ensemble jusqu&rsquo;\u00e0 la fin du lyc\u00e9e et de l&rsquo;universit\u00e9, et nous avons tous deux quitt\u00e9 la m\u00eame universit\u00e9, la Texas A&amp;M University. Il commence une \u00e9cole clinique \u00e0 la fin du printemps et je suis en premi\u00e8re ann\u00e9e d&rsquo;\u00e9tudes sup\u00e9rieures. Il est mon compagnon le plus proche. Nous aimons les m\u00eames livres, la m\u00eame musique (nous vous aimons, Mumford &amp; Sons et Taylor Swift) et le m\u00eame enthousiasme \u00e0 faire ressortir la lumi\u00e8re chez l&rsquo;autre. Nous avons r\u00e9alis\u00e9 que nous devions faire un voyage avant qu&rsquo;il ne commence l&rsquo;\u00e9cole clinique et que les choses ne deviennent tr\u00e8s occup\u00e9es pour nous deux. Nous avons conclu que Banff, en Alberta, au Canada, \u00e9tait le genre de voyage que nous recherchions.<\/p>\n<figure id=\"attachment_28820\" aria-describedby=\"caption-attachment-28820\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28820 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"700\" height=\"464\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/MeganandKevin2.png\"><figcaption id=\"caption-attachment-28820\" class=\"wp-caption-text\">Photography &#8211; Justine Russo Photography<\/figcaption><\/figure>\n<h2 style=\"text-align: justify;\">Comment Kevin a fait sa demande<\/h2>\n<p>Un soir, dans le parc national de Banff, nous nous trouvions au point le plus \u00e9lev\u00e9 d&rsquo;un amas de rochers qui donnait sur l&rsquo;un des lacs les plus ravissants dont j&rsquo;avais jamais r\u00eav\u00e9. Alors que le soleil commen\u00e7ait \u00e0 se coucher, nous avons d\u00e9cid\u00e9 de prendre une photo ensemble. Nous avons demand\u00e9 \u00e0 une femme pr\u00e8s de nous si elle pouvait prendre une photo de nous ; \u00e0 mon grand d\u00e9sarroi, il s&rsquo;agissait d&rsquo;une photographe pr\u00e9arrang\u00e9e ! Nous nous sommes \u00e9loign\u00e9s des groupes pour nous rendre dans une zone semi-priv\u00e9e pr\u00e8s du lac. Apr\u00e8s avoir pris notre photo, elle est partie et Kevin lui a demand\u00e9 de me prendre en photo, mais cette fois-ci, une photo de moi regardant l&rsquo;eau en lui tournant le dos.<\/p>\n<p>Apr\u00e8s qu&rsquo;elle ait pris la photo, j&rsquo;ai pivot\u00e9 et je l&rsquo;ai vu \u00e0 genoux, avec une bague dans la main ! J&rsquo;ai \u00e9t\u00e9 totalement surprise. J&rsquo;ai entendu le bruit d&rsquo;un appareil photo et j&rsquo;ai compris qu&rsquo;il avait demand\u00e9 \u00e0 un cam\u00e9raman de faire un reportage. Apr\u00e8s qu&rsquo;il m&rsquo;ait demand\u00e9 de l&rsquo;\u00e9pouser, j&rsquo;ai \u00e9videmment dit oui !<\/p>\n<figure id=\"attachment_28819\" aria-describedby=\"caption-attachment-28819\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28819 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"700\" height=\"465\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/MeganandKevin3.png\"><figcaption id=\"caption-attachment-28819\" class=\"wp-caption-text\">Photography &#8211; Justine Russo Photography<\/figcaption><\/figure>\n<figure id=\"attachment_28818\" aria-describedby=\"caption-attachment-28818\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28818 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"700\" height=\"463\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/MeganandKevin4.png\"><figcaption id=\"caption-attachment-28818\" class=\"wp-caption-text\">Photography &#8211; Justine Russo Photography<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">J&rsquo;allais remercier la photographe qui avait pris le meilleur clich\u00e9 de ma vie, lorsqu&rsquo;elle et Kevin m&rsquo;ont expliqu\u00e9 que l&rsquo;impr\u00e9vu n&rsquo;\u00e9tait pas termin\u00e9 ! Ils avaient organis\u00e9 une incroyable s\u00e9ance de fian\u00e7ailles pour moi ! Ils ont pr\u00e9cis\u00e9 qu&rsquo;ils avaient \u00e9t\u00e9 en contact pendant pr\u00e8s de six mois pour organiser tout cela et qu&rsquo;ils s&rsquo;\u00e9taient m\u00eame rencontr\u00e9s par Skype \u00e0 plusieurs reprises. C&rsquo;\u00e9tait tellement extraordinaire d&rsquo;avoir quelqu&rsquo;un que je n&rsquo;avais jamais rencontr\u00e9 qui m&rsquo;aidait \u00e0 rendre ce jour superbe pour moi.<\/p>\n<figure id=\"attachment_28817\" aria-describedby=\"caption-attachment-28817\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28817 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"700\" height=\"463\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/MeganandKevin5.png\"><figcaption id=\"caption-attachment-28817\" class=\"wp-caption-text\">Photography &#8211; Justine Russo Photography<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Nous sommes all\u00e9s \u00e0 la voiture pour que je puisse prendre quelques affaires pour me changer et me refaire une beaut\u00e9 quand Kevin m&rsquo;a donn\u00e9 deux sacs, l&rsquo;un de sa m\u00e8re et l&rsquo;autre de lui. Dans le sac de sa m\u00e8re se trouvait une merveilleuse robe blanche et dans celui de Kevin une paire de chaussures dont j&rsquo;avais d\u00e9sesp\u00e9r\u00e9ment besoin. J&rsquo;avais l&rsquo;impression d&rsquo;\u00eatre une v\u00e9ritable princesse ! Nous avons pris des photos tout autour du lac. Notre photographe, Justine, \u00e9tait superbe. Je n&rsquo;aime pas trop que l&rsquo;on s&rsquo;int\u00e9resse \u00e0 moi, mais elle nous a fait nous sentir si bien et si calmes. Kevin a r\u00e9v\u00e9l\u00e9 qu&rsquo;il avait pass\u00e9 des heures \u00e0 chercher le cam\u00e9raman id\u00e9al et qu&rsquo;il \u00e9tait certain, sans l&rsquo;ombre d&rsquo;un doute, que Justine \u00e9tait la meilleure de tout le Canada. Je ne peux qu&rsquo;\u00eatre d&rsquo;accord. Apr\u00e8s avoir termin\u00e9 au lac Moraine, nous nous sommes dirig\u00e9s vers le lac Louise, o\u00f9 j&rsquo;ai enfil\u00e9 ma nouvelle tenue et pris beaucoup plus de photos de la demande en mariage. Toute la soir\u00e9e a \u00e9t\u00e9 un v\u00e9ritable r\u00eave.<\/p>\n<figure id=\"attachment_28821\" aria-describedby=\"caption-attachment-28821\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28821 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"700\" height=\"465\" data-src=\"https:\/\/perfectvenue.eu\/wp-content\/uploads\/MeganandKevin1.png\"><figcaption id=\"caption-attachment-28821\" class=\"wp-caption-text\">Photography &#8211; Justine Russo Photography<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Je me sens tellement chanceuse d&rsquo;avoir quelqu&rsquo;un qui pense suffisamment \u00e0 moi pour organiser une journ\u00e9e aussi exceptionnelle. J&rsquo;ai h\u00e2te d&rsquo;\u00e9pouser mon nouveau fianc\u00e9, Kevin !<\/p>\n<h3>Cr\u00e9dits:<\/h3>\n<p><a href=\"http:\/\/justine-russo.com\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Justine Russo<\/a>\u00a0|\u00a0JUSTINE RUSSO PHOTOGRAPHY<\/p>\n<span class=\"tags-links\"><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/engagement-session\/\" rel=\"tag\">engagement session<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/fotografa-de-bodas\/\" rel=\"tag\">fotografa de bodas<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/historia-de-amor\/\" rel=\"tag\">historia de amor<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/love-story\/\" rel=\"tag\">love story<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/marriage-proposal\/\" rel=\"tag\">Marriage Proposal<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/pedida-de-mano\/\" rel=\"tag\">pedida de mano<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/prometidos\/\" rel=\"tag\">prometidos<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/proposal\/\" rel=\"tag\">proposal<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/proposal-photographer\/\" rel=\"tag\">proposal photographer<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/proposicion\/\" rel=\"tag\">proposicion<\/a><a href=\"https:\/\/perfectvenue.eu\/fr\/tag\/wedding-proposal\/\" rel=\"tag\">wedding proposal<\/a><\/span>","protected":false},"excerpt":{"rendered":"<p>Kevin et moi nous sommes rencontr\u00e9s dans le lyc\u00e9e de notre quartier au Texas. J&rsquo;avais entendu parler de lui \u00e0 l&rsquo;\u00e9cole parce qu&rsquo;il portait une veste Harry Potter et que j&rsquo;ADORE tout ce qui a trait \u00e0 Harry Potter. Un jour, nous avons eu l&rsquo;occasion de nous rencontrer et nous avons commenc\u00e9 \u00e0 parler&#8230;.<\/p>\n","protected":false},"author":10012,"featured_media":28817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","footnotes":""},"categories":[1347],"tags":[1816,1024,2002,1817,1818,774,2004,1810,1815,2003,773],"class_list":["post-28816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destanation-marriage-proposal","tag-engagement-session","tag-fotografa-de-bodas","tag-historia-de-amor","tag-love-story","tag-marriage-proposal","tag-pedida-de-mano","tag-prometidos","tag-proposal","tag-proposal-photographer","tag-proposicion","tag-wedding-proposal"],"_links":{"self":[{"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/posts\/28816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/users\/10012"}],"replies":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/comments?post=28816"}],"version-history":[{"count":0,"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/posts\/28816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/media\/28817"}],"wp:attachment":[{"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/media?parent=28816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/categories?post=28816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perfectvenue.eu\/fr\/wp-json\/wp\/v2\/tags?post=28816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}